{"id":18,"count":12,"description":"","link":"https:\/\/dechilleolifant.nl\/nl\/product-categorie\/care-activities\/","name":"Zorg &amp; Activiteiten","slug":"care-activities","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/dechilleolifant.nl\/nl\/wp-json\/wp\/v2\/product_cat\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dechilleolifant.nl\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dechilleolifant.nl\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/dechilleolifant.nl\/nl\/wp-json\/wp\/v2\/product?product_cat=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}